{"id":64070,"date":"2023-10-12T16:13:46","date_gmt":"2023-10-12T14:13:46","guid":{"rendered":"https:\/\/www.archiviofotoelioconti.it\/?post_type=tnc_col_5_item&#038;p=64070"},"modified":"2023-10-12T16:16:15","modified_gmt":"2023-10-12T14:16:15","slug":"pog0019-campo-a-sole","status":"publish","type":"tnc_col_5_item","link":"https:\/\/www.archiviofotoelioconti.it\/en\/elio-conti\/pog0019-campo-a-sole\/","title":{"rendered":"POG0019 &#8211; Campo a Sole"},"content":{"rendered":"<p>Campo a Sole (d[estra]) da sud-est<\/p>\n","protected":false},"featured_media":64071,"parent":0,"menu_order":0,"template":"","format":"standard","class_list":["post-64070","tnc_col_5_item","type-tnc_col_5_item","status-publish","format-standard","has-post-thumbnail","hentry","tnc_tax_1502-panoramica","tnc_tax_861-poggialvento"],"_links":{"self":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item\/64070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item"}],"about":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/types\/tnc_col_5_item"}],"version-history":[{"count":0,"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item\/64070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/media\/64071"}],"wp:attachment":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/media?parent=64070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}