{"id":64974,"date":"2023-10-13T16:38:04","date_gmt":"2023-10-13T14:38:04","guid":{"rendered":"https:\/\/www.archiviofotoelioconti.it\/?post_type=tnc_col_5_item&#038;p=64974"},"modified":"2023-10-13T16:41:26","modified_gmt":"2023-10-13T14:41:26","slug":"pog0038-pesa-massole","status":"publish","type":"tnc_col_5_item","link":"https:\/\/www.archiviofotoelioconti.it\/en\/elio-conti\/pog0038-pesa-massole\/","title":{"rendered":"POG0038 &#8211; Pesa &#8211; Massole"},"content":{"rendered":"<p>Panoramica dal fondovalle della Pesa (con Massole)<\/p>","protected":false},"featured_media":64975,"parent":0,"menu_order":0,"template":"","format":"standard","class_list":["post-64974","tnc_col_5_item","type-tnc_col_5_item","status-publish","format-standard","has-post-thumbnail","hentry","tnc_tax_1502-panoramica","tnc_tax_861-poggialvento"],"_links":{"self":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item\/64974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item"}],"about":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/types\/tnc_col_5_item"}],"version-history":[{"count":0,"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item\/64974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/media\/64975"}],"wp:attachment":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/media?parent=64974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}