{"id":65682,"date":"2023-10-16T16:37:28","date_gmt":"2023-10-16T14:37:28","guid":{"rendered":"https:\/\/www.archiviofotoelioconti.it\/?post_type=tnc_col_5_item&#038;p=65682"},"modified":"2023-10-16T16:40:23","modified_gmt":"2023-10-16T14:40:23","slug":"pnt0002-montebonello","status":"publish","type":"tnc_col_5_item","link":"https:\/\/www.archiviofotoelioconti.it\/en\/elio-conti\/pnt0002-montebonello\/","title":{"rendered":"PNT0002 &#8211; Montebonello"},"content":{"rendered":"<p>Montebonello (dalla strada sottostante)<\/p>","protected":false},"featured_media":65683,"parent":0,"menu_order":0,"template":"","format":"standard","_links":{"self":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item\/65682"}],"collection":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item"}],"about":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/types\/tnc_col_5_item"}],"version-history":[{"count":0,"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item\/65682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/media\/65683"}],"wp:attachment":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/media?parent=65682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}