{"id":65775,"date":"2023-10-16T16:48:10","date_gmt":"2023-10-16T14:48:10","guid":{"rendered":"https:\/\/www.archiviofotoelioconti.it\/?post_type=tnc_col_5_item&#038;p=65775"},"modified":"2023-10-16T16:51:09","modified_gmt":"2023-10-16T14:51:09","slug":"pnt0004-montebonello","status":"publish","type":"tnc_col_5_item","link":"https:\/\/www.archiviofotoelioconti.it\/en\/elio-conti\/pnt0004-montebonello\/","title":{"rendered":"PNT0004 &#8211; Montebonello"},"content":{"rendered":"<p>Montebonello (da sud-ovest)<\/p>","protected":false},"featured_media":65776,"parent":0,"menu_order":0,"template":"","format":"standard","_links":{"self":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item\/65775"}],"collection":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item"}],"about":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/types\/tnc_col_5_item"}],"version-history":[{"count":0,"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item\/65775\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/media\/65776"}],"wp:attachment":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/media?parent=65775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}