{"id":65959,"date":"2023-10-16T17:26:03","date_gmt":"2023-10-16T15:26:03","guid":{"rendered":"https:\/\/www.archiviofotoelioconti.it\/?post_type=tnc_col_5_item&#038;p=65959"},"modified":"2023-10-16T17:28:43","modified_gmt":"2023-10-16T15:28:43","slug":"pnt0008-montebonello","status":"publish","type":"tnc_col_5_item","link":"https:\/\/www.archiviofotoelioconti.it\/en\/elio-conti\/pnt0008-montebonello\/","title":{"rendered":"PNT0008 &#8211; Montebonello"},"content":{"rendered":"<p>Torre di Montebonello<\/p>","protected":false},"featured_media":65960,"parent":0,"menu_order":0,"template":"","format":"standard","class_list":["post-65959","tnc_col_5_item","type-tnc_col_5_item","status-publish","format-standard","has-post-thumbnail","hentry","tnc_tax_1502-struttura-fortificata","tnc_tax_861-pontassieve"],"_links":{"self":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item\/65959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item"}],"about":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/types\/tnc_col_5_item"}],"version-history":[{"count":0,"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/tnc_col_5_item\/65959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/media\/65960"}],"wp:attachment":[{"href":"https:\/\/www.archiviofotoelioconti.it\/en\/wp-json\/wp\/v2\/media?parent=65959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}